{"id":1236,"date":"2022-04-21T08:04:10","date_gmt":"2022-04-21T08:04:10","guid":{"rendered":"https:\/\/rcto.wpengine.com\/?page_id=1236"},"modified":"2026-01-12T14:21:33","modified_gmt":"2026-01-12T14:21:33","slug":"nous-joindre%ef%bf%bc","status":"publish","type":"page","link":"https:\/\/rcto.ca\/fr\/nous-joindre%ef%bf%bc\/","title":{"rendered":"Nous joindre\ufffc"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbDiscover\u00a0\u00bb module_class=\u00a0\u00bbdiscover-sec\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/rcto.ca\/wp-content\/uploads\/2022\/08\/contact.png\u00a0\u00bb custom_padding=\u00a0\u00bb150px||150px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bboff\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; module_class=\u00a0\u00bbdiscover-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbbanner-text\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<h1>Nous joindre<\/h1>\n<p>[\/et_pb_text][et_pb_text module_class=\u00a0\u00bbdiscover-text1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb18px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<h3 class=\"newhead\" style=\"text-align: center;\"><strong><span class=\"header\"><span>Information g\u00e9n\u00e9rale<\/span><\/span><\/strong><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb200px\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\"><b>Ontario<\/b><\/p>\n<p style=\"text-align: left;\"><span>945, prom. Meyerside<\/span><br \/> <span>Mississauga (Ontario) L5T 1P9<\/span><br \/> <span>T\u00e9l\u00e9phone<\/span>: 1-866-206-0008<br \/> <span>T\u00e9l\u00e9phone<\/span>: 905-795-5388<br \/> Fax: 905-795-5240<br \/> <span>Courriel<\/span>: <a href=\"mailto:info@rcto.ca\">info@rcto.ca<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2886.8999118907263!2d-79.66884458450237!3d43.65025067912146!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x882b3f3936b96869%3A0xe96c557909bac7c1!2s945%20Meyerside%20Dr%2C%20Mississauga%2C%20ON%20L5T%201P9%2C%20Canada!5e0!3m2!1sen!2sin!4v1650275946524!5m2!1sen!2sin\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb200px\u00a0\u00bb height_tablet=\u00a0\u00bb\u00a0\u00bb height_phone=\u00a0\u00bb\u00a0\u00bb height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]<\/p>\n<p><b>Toronto Office c\/o Center for Social Innovation<\/b><\/p>\n<p>192 Spadina Avenue<br \/> Toronto (Ontario) M5T 2C2<br \/> <span>T\u00e9l\u00e9phone<\/span>: 905-795-5388<br \/> Fax: 905-795-5240<br \/> <span>Courriel<\/span>: <a href=\"mailto:info@rcto.ca\">info@rcto.ca<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2886.9072813197527!2d-79.39940824862309!3d43.65009736054634!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x882b34dca6232863%3A0x297d8e20c1df4eae!2s192%20Spadina%20Ave.%2C%20Toronto%2C%20ON%20M5T%203B3!5e0!3m2!1sen!2sca!4v1654274620743!5m2!1sen!2sca\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb188px\u00a0\u00bb height_tablet=\u00a0\u00bb\u00a0\u00bb height_phone=\u00a0\u00bb\u00a0\u00bb height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<div class=\"x_elementToProof\"><b data-olk-copy-source=\"MessageBody\">Bureau d&rsquo;Ottawa<\/b><\/div>\n<div class=\"x_elementToProof\"><span>38 Auriga Drive<br \/>Ottawa, Ontario, K2E A85<br \/>Telephone: 613-286-0662<br \/>Fax: 905-795-5240<br \/>Email: <a href=\"info@rcto.ca\">info<\/a><\/span><span><a href=\"info@rcto.ca\">@rcto.ca<\/a><a id=\"OWA139a11d7-c65d-70ca-90ee-da012b13db15\" class=\"x_OWAAutoLink\" href=\"mailto:info@rcto.ca\" data-linkindex=\"1\" title=\"mailto:info@rcto.ca\"><\/a><\/span><\/div>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb]<\/p>\n<p><strong>Pour des dons d\u2019ordinateurs, communiquez avec :<br \/> Coordonnatrice des dons et de la logistique<\/strong><\/p>\n<p><span>(du lundi au vendredi, de 9 h \u00e0<\/span><v><span>\u00a0<\/span>16 h, sauf les jours de cong\u00e9)<br \/> <span>T\u00e9l\u00e9phone<\/span>: <span>1-866-206-0008<\/span><\/v><br \/> <v><v><span>T\u00e9l\u00e9phone<\/span><\/v>:<span>905-795-5388<\/span><br \/> Fax: <span>905-795-5240<\/span><br \/> <span>Courriel<\/span>: <a href=\"donations@rcto.ca\">donations@rcto.ca<\/a><\/v><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbPrograms\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_module=\u00a0\u00bb1422&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb collapsed=\u00a0\u00bboff\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; module_class=\u00a0\u00bbpro-row-1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; module_class=\u00a0\u00bbprogram-col1 program-no-height\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#47aa66&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/rcto.wpengine.com\/wp-content\/uploads\/2022\/03\/pro1.png\u00a0\u00bb title_text=\u00a0\u00bbpro1&Prime; module_class=\u00a0\u00bbpro-img\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][et_pb_text module_class=\u00a0\u00bbimpact-text-tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb]<\/p>\n<h4 style=\"text-align: center;\">IMPACTS<\/h4>\n<p style=\"text-align: center;\" >Social. \u00e9conomique. Environnement.<\/p>\n<p style=\"text-align: center;\" class=\"pro-link\"><a href=\"\/fr\/impacts\/\">Savoir plus<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; module_class=\u00a0\u00bbprogram-col2 program-no-height\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#65d3c2&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/rcto.wpengine.com\/wp-content\/uploads\/2022\/07\/pro2.png\u00a0\u00bb title_text=\u00a0\u00bbpro2&Prime; module_class=\u00a0\u00bbpro-img\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb||30px||false|false\u00a0\u00bb]<\/p>\n<h4 style=\"text-align: center;\">INSPIRATION<\/h4>\n<p style=\"text-align: center;\"><span>Ce qui a inspir\u00e9 notre travail<\/span><\/p>\n<p style=\"text-align: center;\" class=\"pro-link\"><a href=\"\/fr\/inspiration\/\">Savoir plus<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; module_class=\u00a0\u00bbprogram-col3 program-no-height\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#febd40&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/rcto.wpengine.com\/wp-content\/uploads\/2022\/08\/Spotlight-352px-X-290px.png\u00a0\u00bb title_text=\u00a0\u00bbSpotlight 352px X 290px\u00a0\u00bb module_class=\u00a0\u00bbpro-img\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][et_pb_text module_class=\u00a0\u00bbpro-text1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb||30px||false|false\u00a0\u00bb]<\/p>\n<h4 style=\"text-align: center;\">PROJECTEUR<\/h4>\n<p style=\"text-align: center;\">Notre reportage<\/p>\n<p style=\"text-align: center;\" class=\"pro-link\"><a href=\"\/fr\/nouvelles\/\">Savoir plus<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbNews\u00a0\u00bb module_class=\u00a0\u00bbblog-sec\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_module=\u00a0\u00bb1423&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb collapsed=\u00a0\u00bboff\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbnews-title\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Nouvelles<\/h2>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb]<style type='text\/css' media='all'>#rt-tpg-container-2600209022 .rt-holder .rt-woo-info .price{color:#0367bf;}body .rt-tpg-container .rt-tpg-isotope-buttons .selected,\n\t\t\t\t\t#rt-tpg-container-2600209022 .layout12 .rt-holder:hover .rt-detail,\n\t\t\t\t\t#rt-tpg-container-2600209022 .isotope8 .rt-holder:hover .rt-detail,\n\t\t\t\t\t#rt-tpg-container-2600209022 .carousel8 .rt-holder:hover .rt-detail,\n\t\t\t\t\t#rt-tpg-container-2600209022 .layout13 .rt-holder .overlay .post-info,\n\t\t\t\t\t#rt-tpg-container-2600209022 .isotope9 .rt-holder .overlay .post-info,\n\t\t\t\t\t#rt-tpg-container-2600209022.rt-tpg-container .layout4 .rt-holder .rt-detail,\n\t\t\t\t\t.rt-modal-2600209022 .md-content,\n\t\t\t\t\t.rt-modal-2600209022 .md-content > .rt-md-content-holder .rt-md-content,\n\t\t\t\t\t.rt-popup-wrap-2600209022.rt-popup-wrap .rt-popup-navigation-wrap,\n\t\t\t\t\t#rt-tpg-container-2600209022 .carousel9 .rt-holder .overlay .post-info{background-color:#0367bf;}#rt-tpg-container-2600209022 .layout5 .rt-holder .overlay, #rt-tpg-container-2600209022 .isotope2 .rt-holder .overlay, #rt-tpg-container-2600209022 .carousel2 .rt-holder .overlay,#rt-tpg-container-2600209022 .layout15 .rt-holder h3, #rt-tpg-container-2600209022 .isotope11 .rt-holder h3, #rt-tpg-container-2600209022 .carousel11 .rt-holder h3, #rt-tpg-container-2600209022 .layout16 .rt-holder h3,\n\t\t\t\t\t#rt-tpg-container-2600209022 .isotope12 .rt-holder h3, #rt-tpg-container-2600209022 .carousel12 .rt-holder h3 {background-color:rgba(3,103,191,0.8);}#rt-tpg-container-2600209022 .read-more a{border-radius:px;}#rt-tpg-container-2600209022 .rt-img-holder img.rt-img-responsive,#rt-tpg-container-2600209022 .rt-img-holder,\n\t\t\t\t\t#rt-tpg-container-2600209022 .rt-post-overlay .post-img,\n\t\t\t\t\t#rt-tpg-container-2600209022 .post-sm .post-img,\n\t\t\t\t\t#rt-tpg-container-2600209022 .rt-post-grid .post-img,\n\t\t\t\t\t#rt-tpg-container-2600209022 .post-img img {border-radius:px;}<\/style><div class='rt-container-fluid rt-tpg-container tpg-shortcode-main-wrapper ' id='rt-tpg-container-2600209022'   data-layout='layout1' data-grid-style='even' data-desktop-col='3'  data-tab-col='2'  data-mobile-col='1' data-sc-id='1287'><div data-title='Loading ...' class='rt-row rt-content-loader   layout1 tpg-even '><p>No post found<\/p><\/div><\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_class=\u00a0\u00bbemail-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#00946d\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1170px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb module_class=\u00a0\u00bbnewsletter\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb]<\/p>\n<h4>Rejoignez notre newsletter par e-mail<\/h4>\n<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1321-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1321\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/1236#wpcf7-f1321-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1321\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1321-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div style=\"display:flex;\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required newsletter-firstname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Pr\u00e9nom\" value=\"\" type=\"text\" name=\"firstname\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required newsletter-lastname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom de famille\" value=\"\" type=\"text\" name=\"lastname\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required newsletter-com\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Soci\u00e9t\u00e9\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email newsletter-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"checkbox-div\">\n\t<p><label> Je suis int\u00e9ress\u00e9 par:<\/label>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"technology\"><span class=\"wpcf7-form-control wpcf7-checkbox newsletter-checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"technology[]\" value=\"Technologie de commande\" \/><span class=\"wpcf7-list-item-label\">Technologie de commande<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"technology[]\" value=\"Don de technologie\" \/><span class=\"wpcf7-list-item-label\">Don de technologie<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner subscribe-button\" type=\"submit\" value=\"S&#039;abonner\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbDiscover\u00a0\u00bb module_class=\u00a0\u00bbdiscover-sec\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/rcto.ca\/wp-content\/uploads\/2022\/08\/contact.png\u00a0\u00bb custom_padding=\u00a0\u00bb150px||150px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bboff\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; module_class=\u00a0\u00bbdiscover-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbbanner-text\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb] Nous joindre [\/et_pb_text][et_pb_text module_class=\u00a0\u00bbdiscover-text1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb18px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb] Information g\u00e9n\u00e9rale [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-1236","page","type-page","status-publish","hentry"],"featured_image_src":null,"featured_image_src_square":null,"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"content","author_link":"https:\/\/rcto.ca\/fr\/author\/content\/"},"rttpg_comment":0,"rttpg_category":" <a href=\"https:\/\/rcto.ca\/?taxonomy=translation_priority&#038;term=optional\" rel=\"tag\">Optional<\/a>","rttpg_excerpt":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbDiscover\u00a0\u00bb module_class=\u00a0\u00bbdiscover-sec\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/rcto.ca\/wp-content\/uploads\/2022\/08\/contact.png\u00a0\u00bb custom_padding=\u00a0\u00bb150px||150px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bboff\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; module_class=\u00a0\u00bbdiscover-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbbanner-text\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb] Nous joindre [\/et_pb_text][et_pb_text module_class=\u00a0\u00bbdiscover-text1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb18px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb] Information g\u00e9n\u00e9rale [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime;\u2026","_links":{"self":[{"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/pages\/1236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/comments?post=1236"}],"version-history":[{"count":0,"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/pages\/1236\/revisions"}],"wp:attachment":[{"href":"https:\/\/rcto.ca\/fr\/wp-json\/wp\/v2\/media?parent=1236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}